{"id":10734,"date":"2022-06-07T17:27:29","date_gmt":"2022-06-07T17:27:29","guid":{"rendered":"https:\/\/aexis-medical.com\/startpagina\/"},"modified":"2026-03-23T17:40:54","modified_gmt":"2026-03-23T17:40:54","slug":"startpagina","status":"publish","type":"page","link":"https:\/\/aexis-medical.com\/nl\/","title":{"rendered":"startpagina"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10734\" class=\"elementor elementor-10734 elementor-2760\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-5889d75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5889d75\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4bb6af8\" data-id=\"4bb6af8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acd1b77 ui-e-a-animate elementor-widget elementor-widget-highlighted-text\" data-id=\"acd1b77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"highlighted-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <h1 class=\"ui-e--highlighted-text\">\n            <span class=\"ui-e-headline-text elementor-repeater-item-59b8ee8\">Innovatieve Oplossingen voor <\/span><span class=\"ui-e-headline-text elementor-repeater-item-8add9ac ui-e-headline-stroke1\">\n\t\t\t\t\t\t\t\t\t<span class=\"whitespace\"><\/span>\n                                    <span>\n                                        <span class=\"ui-e-headline-text ui-e-headline-highlighted\">Slimmere Gezondheidszorg.<\/span><span class=\"uicore-svg-wrapper\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 500 150\" preserveAspectRatio=\"none\"><path d='M15.2,133.3L15.2,133.3c121.9-7.6,244-9.9,366.1-6.8c34.6,0.9,69.1,2.3,103.7,4' \/><\/svg><\/span><\/span> <span class=\"whitespace\"> <\/span><\/span>        <\/h1>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-082121d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"082121d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Met meer dan 20 jaar expertise zetten wij ons in om uw werk eenvoudiger en veiliger te maken. Onze oplossingen stroomlijnen de workflows in het ziekenhuis, verbeteren de veiligheid van de pati\u00ebnt en vergroten de effici\u00ebntie. Alles op maat gemaakt om te voldoen aan uw unieke behoeften.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe1d9ab elementor-widget elementor-widget-spacer\" data-id=\"fe1d9ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ab756 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"45ab756\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacteer ons<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58d871c elementor-widget__width-auto elementor-widget elementor-widget-bdt-animated-link\" data-id=\"58d871c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-animated-link.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"bdt-ep-animated-link bdt-ep-animated-link--iocaste\" href=\"https:\/\/aexis-medical.com\/klantenverhalen\/\">\n\t\t\t\t<span>Klantverhalen \u2192<\/span>\n\t\t\t\t<svg class=\"bdt-link__graphic bdt-link__graphic--slide\" width=\"300%\" height=\"100%\" viewBox=\"0 0 1200 60\" preserveAspectRatio=\"none\">\n\t\t\t\t\t<path d=\"M0,56.5c0,0,298.666,0,399.333,0C448.336,56.5,513.994,46,597,46c77.327,0,135,10.5,200.999,10.5c95.996,0,402.001,0,402.001,0\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/a>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b7c2315 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b7c2315\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4be6c54 bdt-backdrop-filter-yes\" data-id=\"4be6c54\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b28a5c9 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"b28a5c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-b28a5c9&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:10,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:&quot;2&quot;,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;+&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content bdt-flex-inline bdt-flex-middle\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-b28a5c9\" >\n\t\t\t\t\t10\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tactieve landen\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-24e7d9b bdt-backdrop-filter-yes\" data-id=\"24e7d9b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09bf993 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"09bf993\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-09bf993&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:20,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:&quot;2&quot;,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;+&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content bdt-flex-inline bdt-flex-middle\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-09bf993\" >\n\t\t\t\t\t20\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tjaren ervaring\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1cb4446 bdt-backdrop-filter-yes\" data-id=\"1cb4446\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcaa2d9 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-bdt-advanced-counter\" data-id=\"dcaa2d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter\" data-settings=\"{&quot;id&quot;:&quot;bdt-ep-advanced-counter-data-dcaa2d9&quot;,&quot;countStart&quot;:1,&quot;countNumber&quot;:200,&quot;language&quot;:[&quot;0&quot;,&quot;1&quot;,&quot;2&quot;,&quot;3&quot;,&quot;4&quot;,&quot;5&quot;,&quot;6&quot;,&quot;7&quot;,&quot;8&quot;,&quot;9&quot;],&quot;duration&quot;:&quot;2&quot;,&quot;useEasing&quot;:&quot;yes&quot;,&quot;useGrouping&quot;:&quot;no&quot;,&quot;decimalSymbol&quot;:&quot;.&quot;,&quot;counterSuffix&quot;:&quot;+&quot;}\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-content bdt-flex-inline bdt-flex-middle\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-counter-number\">\n\t\t\t\t<span class=\"bdt-count-this\" id=\"bdt-ep-advanced-counter-data-dcaa2d9\" >\n\t\t\t\t\t200\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p\t\t\t\t\t\tclass=\"bdt-ep-advanced-counter-text\">\n\t\t\t\t\t\tsuccesvolle implementaties\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9acd65\" data-id=\"e9acd65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2002c02 elementor-widget elementor-widget-spacer\" data-id=\"2002c02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-61d3b20 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"61d3b20\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-265649b\" data-id=\"265649b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-153b6d3 elementor-widget elementor-widget-image-carousel\" data-id=\"153b6d3\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"brand\" data-settings=\"{&quot;slides_to_show&quot;:&quot;7&quot;,&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 van 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image smush-dimensions lazyload\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp\" alt=\"az-alma-logo.webp\" width=\"320\" style=\"--smush-image-width: 320px; --smush-image-aspect-ratio: 320\/200;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp 320w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo-300x188.webp 300w\" data-sizes=\"auto\" data-original-sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 van 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image smush-dimensions lazyload\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/Iris-sud-kleur.webp\" alt=\"Iris-sud-kleur\" width=\"320\" style=\"--smush-image-width: 320px; --smush-image-aspect-ratio: 320\/200;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/Iris-sud-kleur.webp 320w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/Iris-sud-kleur-300x188.webp 300w\" data-sizes=\"auto\" data-original-sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 van 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image smush-dimensions lazyload\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/logo-chirec-new.png\" alt=\"logo-chirec-new\" width=\"600\" style=\"--smush-image-width: 600px; --smush-image-aspect-ratio: 600\/386;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/logo-chirec-new.png 600w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/logo-chirec-new-300x193.png 300w\" data-sizes=\"auto\" data-original-sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 van 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image smush-dimensions lazyload\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/chc-kleur.webp\" alt=\"chc-kleur\" width=\"320\" style=\"--smush-image-width: 320px; --smush-image-aspect-ratio: 320\/200;\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/chc-kleur.webp 320w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/chc-kleur-300x188.webp 300w\" data-sizes=\"auto\" data-original-sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-b9a8991 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9a8991\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f13911\" data-id=\"9f13911\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bf21eb elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7bf21eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">De XLine oplossingen integreren naadloos departement overstijgende processen.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30727ba elementor-widget__width-initial elementor-widget elementor-widget-bdt-animated-link\" data-id=\"30727ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-animated-link.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"bdt-ep-animated-link bdt-ep-animated-link--iocaste\" href=\"\/en\/solutions\/\">\n\t\t\t\t<span>Meer over XLine\u2192<\/span>\n\t\t\t\t<svg class=\"bdt-link__graphic bdt-link__graphic--slide\" width=\"300%\" height=\"100%\" viewBox=\"0 0 1200 60\" preserveAspectRatio=\"none\">\n\t\t\t\t\t<path d=\"M0,56.5c0,0,298.666,0,399.333,0C448.336,56.5,513.994,46,597,46c77.327,0,135,10.5,200.999,10.5c95.996,0,402.001,0,402.001,0\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/a>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"ep-section-eql-height elementor-section elementor-top-section elementor-element elementor-element-d3e35de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" bdt-height-match=\"target: .ep-section-eql-height .elementor-element .elementor-widget &gt; div\" data-id=\"d3e35de\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5e7b8e5\" data-id=\"5e7b8e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ep-wrapper-link=\"{&quot;url&quot;:&quot;\\\/en\\\/solution\\\/xline-steri-for-csa\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"bdt-element-link elementor-element elementor-element-20b4ad5 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"20b4ad5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"2479\" src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Sterri-v1.0-scaled.png\" class=\"attachment-full size-full\" alt=\"XLine Steri \" srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Sterri-v1.0-scaled.png 2560w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Sterri-v1.0-300x291.png 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Sterri-v1.0-1024x992.png 1024w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Sterri-v1.0-768x744.png 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Sterri-v1.0-1536x1488.png 1536w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Sterri-v1.0-2048x1983.png 2048w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Sterri-v1.0-650x629.png 650w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h4 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tXLine Steri \t\t\t\t<\/span>\n\t\t\t<\/h4>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">slimmer sterilisatiebeheer<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3734d3e\" data-id=\"3734d3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ep-wrapper-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/aexis-medical.com\\\/en\\\/solution\\\/xline-or-for-operation-quarter\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"bdt-element-link elementor-element elementor-element-30f5415 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"30f5415\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:200}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"2479\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-OR-v1.0-scaled.png\" class=\"attachment-full size-full lazyload\" alt=\"XLine OR\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-OR-v1.0-scaled.png 2560w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-OR-v1.0-300x291.png 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-OR-v1.0-1024x992.png 1024w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-OR-v1.0-768x744.png 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-OR-v1.0-1536x1488.png 1536w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-OR-v1.0-2048x1983.png 2048w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-OR-v1.0-650x629.png 650w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/2479;\" data-original-sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h4 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tXLine OR\t\t\t\t<\/span>\n\t\t\t<\/h4>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Maximale effici\u00ebntie voor het OK<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8b9cabe\" data-id=\"8b9cabe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ep-wrapper-link=\"{&quot;url&quot;:&quot;\\\/en\\\/solution\\\/xline-endo-for-endoscopy\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"bdt-element-link elementor-element elementor-element-8a8a084 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"8a8a084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"2479\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Endo-v1.0-scaled.png\" class=\"attachment-full size-full lazyload\" alt=\"XLine Endo\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Endo-v1.0-scaled.png 2560w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Endo-v1.0-300x291.png 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Endo-v1.0-1024x992.png 1024w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Endo-v1.0-768x744.png 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Endo-v1.0-1536x1488.png 1536w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Endo-v1.0-2048x1983.png 2048w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Endo-v1.0-650x629.png 650w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/2479;\" data-original-sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h4 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tXLine Endo\t\t\t\t<\/span>\n\t\t\t<\/h4>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Stroomlijnen van het endoscopie proces<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6a6010d\" data-id=\"6a6010d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ep-wrapper-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/aexis-medical.com\\\/en\\\/solution\\\/xline-poly-for-consultation\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"bdt-element-link elementor-element elementor-element-ad653d4 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"ad653d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:400}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"2479\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Poly-v1.0-scaled.png\" class=\"attachment-full size-full lazyload\" alt=\"XLine Poly\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Poly-v1.0-scaled.png 2560w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Poly-v1.0-300x291.png 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Poly-v1.0-1024x992.png 1024w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Poly-v1.0-768x744.png 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Poly-v1.0-1536x1488.png 1536w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Poly-v1.0-2048x1983.png 2048w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Poly-v1.0-650x629.png 650w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/2479;\" data-original-sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h4 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tXLine Poly\t\t\t\t<\/span>\n\t\t\t<\/h4>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Uw uitgebreide planningstool<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-64a64ec\" data-id=\"64a64ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ep-wrapper-link=\"{&quot;url&quot;:&quot;\\\/en\\\/solution\\\/xline-logistics-for-logistics\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"bdt-element-link elementor-element elementor-element-6495af1 bdt-icon-type-image elementor-position-top bdt-icon-effect-none elementor-widget elementor-widget-bdt-advanced-icon-box\" data-id=\"6495af1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"bdt-advanced-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-icon\">\n\t\t\t\t<span class=\"bdt-ep-advanced-icon-box-icon-wrap\">\n\n\n\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"2479\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Logistics-v10-scaled.png\" class=\"attachment-full size-full lazyload\" alt=\"XLine Logistics\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Logistics-v10-scaled.png 2560w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Logistics-v10-300x291.png 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Logistics-v10-1024x992.png 1024w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Logistics-v10-768x744.png 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Logistics-v10-1536x1488.png 1536w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Logistics-v10-2048x1983.png 2048w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/AEXIS-MEDICAL-Icon-Logistics-v10-650x629.png 650w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2560px; --smush-placeholder-aspect-ratio: 2560\/2479;\" data-original-sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\n\t\t\t<div class=\"bdt-ep-advanced-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<h4 class=\"bdt-ep-advanced-icon-box-title ep-title-\">\n\t\t\t\t<span >\n\t\t\t\t\tXLine Logistics\t\t\t\t<\/span>\n\t\t\t<\/h4>\n\t\t\n\n\t\t\n\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-advanced-icon-box-description\">\n\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Volledig ge\u00efntegreerde logistieke oplossing<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9436741 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9436741\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a444e0\" data-id=\"2a444e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6862205 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6862205\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"718\" height=\"437\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2025\/08\/XLine-Scanning-Illustration-gun-metal.svg\" class=\"attachment-full size-full wp-image-9320 lazyload\" alt=\"Illustration of the XLine scanning system in gun metal finish, showing a linear scanning arm designed for medical and industrial imaging applications.\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 718px; --smush-placeholder-aspect-ratio: 718\/437;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a532a47\" data-id=\"a532a47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81544e3 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"81544e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>XLine is de naam van het platform waarop alle oplossingen van Aexis Medical zijn gebouwd. Als ge\u00efntegreerd ERP-platform verbindt het naadloos talrijke gespecialiseerde modules, die elk een specifieke oplossing vertegenwoordigen voor een bepaald proces, workflow of afdeling.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a410e elementor-widget elementor-widget-button\" data-id=\"d9a410e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_delay&quot;:400}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aexis-medical.com\/en\/solutions\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Meer over XLine<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-0339ebd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0339ebd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-628c651\" data-id=\"628c651\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f12cc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f12cc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f85a46\" data-id=\"5f85a46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-915af7b elementor-widget elementor-widget-heading\" data-id=\"915af7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Klantverhalen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5788cde\" data-id=\"5788cde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5eb0ac elementor-widget__width-auto elementor-widget elementor-widget-bdt-animated-link\" data-id=\"e5eb0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-animated-link.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"bdt-ep-animated-link bdt-ep-animated-link--iocaste\" href=\"\/en\/customer-stories\/\">\n\t\t\t\t<span>Klantverhalen \u2192<\/span>\n\t\t\t\t<svg class=\"bdt-link__graphic bdt-link__graphic--slide\" width=\"300%\" height=\"100%\" viewBox=\"0 0 1200 60\" preserveAspectRatio=\"none\">\n\t\t\t\t\t<path d=\"M0,56.5c0,0,298.666,0,399.333,0C448.336,56.5,513.994,46,597,46c77.327,0,135,10.5,200.999,10.5c95.996,0,402.001,0,402.001,0\"><\/path>\n\t\t\t\t<\/svg>\n\t\t\t<\/a>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-659feea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"659feea\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2419098\" data-id=\"2419098\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6adee28 bdt-custom-gallery-skin-fedara-style-center elementor-widget elementor-widget-bdt-post-gallery\" data-id=\"6adee28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"bdt-post-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-post-gallery-wrapper\">\n\n\t\t\t\t\t\t<div id=\"bdt-post-gallery6adee28\" class=\"bdt-post-gallery bdt-ep-grid-filter-container bdt-post-gallery-skin-default bdt-grid bdt-grid-medium\" data-bdt-grid=\"\" data-settings=\"{&quot;id&quot;:&quot;#bdt-post-gallery6adee28&quot;,&quot;tilt_show&quot;:false,&quot;tilt_scale&quot;:false}\">\n\n\t\t\t\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle bdt-width-1-1 bdt-width-1-2@s bdt-width-1-3@m\">\n\t\t\t<div class=\"bdt-post-gallery-inner\" >\n\t\t\t\t\t\t<div class=\"bdt-gallery-thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"200\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/CHIREC-Groupe--300x200.jpeg\" class=\"attachment-medium size-medium lazyload\" alt=\"Optimalisatie van de OK en Sterilisatie workflow bij de CHIREC Ziekenhuisgroep\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/CHIREC-Groupe--300x200.jpeg 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/CHIREC-Groupe--650x434.jpeg 650w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/CHIREC-Groupe-.jpeg 750w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-post-gallery-content\">\n\t\t\t\t<div class=\"bdt-gallery-content-inner\">\n\t\t\t\t\t\t\t<a class=\"bdt-post-gallery-title-link\" href=\"https:\/\/aexis-medical.com\/nl\/testimonial\/chirec\/\" >\n\t\t\t<h4 class=\"bdt-gallery-item-title bdt-margin-remove\">\n\t\t\t\tOptimalisatie van de OK en Sterilisatie workflow bij de CHIREC Ziekenhuisgroep\t\t\t<\/h4>\n\t\t<\/a>\n\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link bdt-link-icon\"\n\t\t\t\t\t\t\t\t\thref=\"https:\/\/aexis-medical.com\/nl\/testimonial\/chirec\/\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-icon-link\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle bdt-width-1-1 bdt-width-1-2@s bdt-width-1-3@m\">\n\t\t\t<div class=\"bdt-post-gallery-inner\" >\n\t\t\t\t\t\t<div class=\"bdt-gallery-thumbnail bdt-gallery-thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/iris-afbeelding-1-300x300.webp\" class=\"attachment-medium size-medium lazyload\" alt=\"Verbeteren van de effici\u00ebntie van OK&#8217;s op 4 Sites bij Iris-Sud Ziekenhuis Groep\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/iris-afbeelding-1-300x300.webp 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/iris-afbeelding-1-1024x1024.webp 1024w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/iris-afbeelding-1-150x150.webp 150w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/iris-afbeelding-1-768x768.webp 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/iris-afbeelding-1-650x650.webp 650w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/iris-afbeelding-1.webp 1156w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-post-gallery-content\">\n\t\t\t\t<div class=\"bdt-gallery-content-inner\">\n\t\t\t\t\t\t\t<a class=\"bdt-post-gallery-title-link\" href=\"https:\/\/aexis-medical.com\/nl\/testimonial\/iris-sud\/\" >\n\t\t\t<h4 class=\"bdt-gallery-item-title bdt-margin-remove\">\n\t\t\t\tVerbeteren van de effici\u00ebntie van OK&#8217;s op 4 Sites bij Iris-Sud Ziekenhuis Groep\t\t\t<\/h4>\n\t\t<\/a>\n\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link bdt-link-icon\"\n\t\t\t\t\t\t\t\t\thref=\"https:\/\/aexis-medical.com\/nl\/testimonial\/iris-sud\/\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-icon-link\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle bdt-width-1-1 bdt-width-1-2@s bdt-width-1-3@m\">\n\t\t\t<div class=\"bdt-post-gallery-inner\" >\n\t\t\t\t\t\t<div class=\"bdt-gallery-thumbnail bdt-gallery-thumbnail bdt-gallery-thumbnail\">\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"200\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-bg-300x200.webp\" class=\"attachment-medium size-medium lazyload\" alt=\"Optimaliseren van OK Planning en Traceerbaarheid van Instrumenten in AZ Alma Ziekenhuis\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-bg-300x200.webp 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-bg-1024x683.webp 1024w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-bg-768x512.webp 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-bg-1536x1024.webp 1536w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-bg-650x433.webp 650w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-bg.webp 1920w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t<\/div>\n\t\t\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-post-gallery-content\">\n\t\t\t\t<div class=\"bdt-gallery-content-inner\">\n\t\t\t\t\t\t\t<a class=\"bdt-post-gallery-title-link\" href=\"https:\/\/aexis-medical.com\/nl\/testimonial\/az-alma\/\" >\n\t\t\t<h4 class=\"bdt-gallery-item-title bdt-margin-remove\">\n\t\t\t\tOptimaliseren van OK Planning en Traceerbaarheid van Instrumenten in AZ Alma Ziekenhuis\t\t\t<\/h4>\n\t\t<\/a>\n\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link bdt-link-icon\"\n\t\t\t\t\t\t\t\t\thref=\"https:\/\/aexis-medical.com\/nl\/testimonial\/az-alma\/\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-icon-link\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc11cd2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cc11cd2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d370574\" data-id=\"d370574\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d337859 elementor-widget elementor-widget-heading\" data-id=\"d337859\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wat zeggen onze klanten.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf37cfb bdt-navigation-type-dots bdt-item-match-height--yes bdt-carousel-style-carousel elementor-widget elementor-widget-bdt-review-card-carousel\" data-id=\"cf37cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-review-card-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"bdt-review-card-carousel-cf37cfb\" class=\"bdt-dots-align-bottom-center bdt-review-card-carousel\" data-settings=\"{&quot;autoplay&quot;:{&quot;delay&quot;:5000,&quot;disableOnInteraction&quot;:false},&quot;loop&quot;:true,&quot;speed&quot;:500,&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1,&quot;spaceBetween&quot;:20,&quot;effect&quot;:&quot;carousel&quot;,&quot;breakpoints&quot;:{&quot;767&quot;:{&quot;slidesPerView&quot;:2,&quot;spaceBetween&quot;:20,&quot;slidesPerGroup&quot;:1},&quot;1023&quot;:{&quot;slidesPerView&quot;:4,&quot;spaceBetween&quot;:20,&quot;slidesPerGroup&quot;:1}},&quot;navigation&quot;:{&quot;nextEl&quot;:&quot;#bdt-review-card-carousel-cf37cfb .bdt-navigation-next&quot;,&quot;prevEl&quot;:&quot;#bdt-review-card-carousel-cf37cfb .bdt-navigation-prev&quot;},&quot;pagination&quot;:{&quot;el&quot;:&quot;#bdt-review-card-carousel-cf37cfb .swiper-pagination&quot;,&quot;type&quot;:&quot;bullets&quot;,&quot;clickable&quot;:&quot;true&quot;,&quot;dynamicBullets&quot;:false},&quot;scrollbar&quot;:{&quot;el&quot;:&quot;#bdt-review-card-carousel-cf37cfb .swiper-scrollbar&quot;,&quot;hide&quot;:&quot;true&quot;},&quot;coverflowEffect&quot;:{&quot;rotate&quot;:50,&quot;stretch&quot;:0,&quot;depth&quot;:100,&quot;modifier&quot;:1,&quot;slideShadows&quot;:true}}\">\n\t\t\t<div class=\"swiper-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Review Card Carousel\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-item swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-image bdt-image-mask\">\n\n\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/Fred.jpeg\" class=\"attachment-medium size-medium lazyload\" alt=\"Fr\u00e9d\u00e9ric Cattoor\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/Fred.jpeg 200w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/Fred-150x150.jpeg 150w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 200px; --smush-placeholder-aspect-ratio: 200\/200;\" data-original-sizes=\"(max-width: 200px) 100vw, 200px\" \/>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"bdt-ep-review-card-carousel-content\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3\t\t\t\tclass=\"bdt-ep-review-card-carousel-name\">\n\t\t\t\tFr\u00e9d\u00e9ric Cattoor\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-job-title\">\n\t\t\t\tMiddenkader en Verpleegkundige PCI (Delta)\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-text bdt-ep-read-more-text\" data-read-more=\"{&quot;words_length&quot;:20}\">\n\t\t\t\t<p>\"We hebben XLine om verschillende redenen gekozen: het is configureerbaar tot in de kleinste details, biedt realtime operatiekamerbeheer en maakt het mogelijk om gedetailleerde statistieken over onze activiteiten te genereren. Dankzij het SteriLine-module is het mogelijk om het gesteriliseerde materiaal nauwkeurig en geautomatiseerd te traceren.<br \/><br \/>Een andere belangrijke reden is natuurlijk de ondersteuning door een team van dynamische en beschikbare professionals. Dankzij dit verliep de implementatie zonder problemen.\"<\/p>\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-item swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-image bdt-image-mask\">\n\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"292\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/person-doctor-bg2-300x292.webp\" class=\"attachment-medium size-medium lazyload\" alt=\"Marc Van der Weyde\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/person-doctor-bg2-300x292.webp 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/person-doctor-bg2-1024x998.webp 1024w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/person-doctor-bg2-768x748.webp 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/person-doctor-bg2-650x633.webp 650w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/person-doctor-bg2.webp 1059w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/292;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"bdt-ep-review-card-carousel-content\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3\t\t\t\tclass=\"bdt-ep-review-card-carousel-name\">\n\t\t\t\tMarc Van der Weyde\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-job-title\">\n\t\t\t\tAZ Alma Eeklo\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-text bdt-ep-read-more-text\" data-read-more=\"{&quot;words_length&quot;:20}\">\n\t\t\t\t<p>De implementatie is zeer vlot verlopen. Medewerkers van Aexis Medical kennen hun toepassing door en door en zijn steeds bereid tot overleg en aanpassing van de software.<\/p>\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-item swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-image bdt-image-mask\">\n\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/1644948282708-300x300.jpeg\" class=\"attachment-medium size-medium lazyload\" alt=\"Margaux Vachiery\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/1644948282708-300x300.jpeg 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/1644948282708-150x150.jpeg 150w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/1644948282708-768x768.jpeg 768w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/1644948282708-650x650.jpeg 650w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/1644948282708.jpeg 800w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"bdt-ep-review-card-carousel-content\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3\t\t\t\tclass=\"bdt-ep-review-card-carousel-name\">\n\t\t\t\tMargaux Vachiery\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-job-title\">\n\t\t\t\tCo\u00f6rdinator voor de Operatiekwartieren\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-text bdt-ep-read-more-text\" data-read-more=\"{&quot;words_length&quot;:20}\">\n\t\t\t\t<p>\u201cOp de dag van de implementatie hebben we de software op hetzelfde tijdstip gelanceerd in onze 4 operatiekwartieren, wat op zichzelf al een uitdaging was.<\/p>\n<p>We waren voorbereid op een stressvolle en moeilijke dag, maar dat was helemaal niet het geval. Iedereen begreep zijn rol en de impact van zijn werk, en alles verliep vlekkeloos.<\/p>\n<p>Het was een waardevolle ervaring die ons zal helpen bij de implementatie van toekomstige projecten.\"<\/p>\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-item swiper-slide\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-image bdt-image-mask\">\n\n\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" data-src=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/oger-300x300.jpeg\" class=\"attachment-medium size-medium lazyload\" alt=\"Olivier Oger\" data-srcset=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/oger-300x300.jpeg 300w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/oger-150x150.jpeg 150w, https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/oger.jpeg 450w\" data-sizes=\"auto\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" data-original-sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"bdt-ep-review-card-carousel-content\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3\t\t\t\tclass=\"bdt-ep-review-card-carousel-name\">\n\t\t\t\tOlivier Oger\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-job-title\">\n\t\t\t\tCo\u00f6rdinator diensten perioperatieve zorg\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-ep-review-card-carousel-text bdt-ep-read-more-text\" data-read-more=\"{&quot;words_length&quot;:20}\">\n\t\t\t\t<p>In het ziekenhuis gebruiken dagelijks meer dan 800 personen uit verschillende beroepen (anesthesisten, chirurgen, verpleegkundigen, logistici, secretaresses, onderhoudspersoneel, managers) dit programma en delen informatie tijdens het hele zorgproces.\u00a0<\/p>\n<p>Aexis Medical biedt ons elke dag de verwachte ondersteuning, wat een grote troef is voor het ziekenhuis dat voortdurend te maken heeft met veranderingen.<\/p>\n<p>CHC Gezondheidsgroep<\/p>\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"bdt-position-z-index bdt-position-bottom-center\">\n\t\t\t\t<div class=\"bdt-dots-container\">\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-627ea44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"627ea44\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5300873\" data-id=\"5300873\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed6407b ui-e-a-animate elementor-widget elementor-widget-highlighted-text\" data-id=\"ed6407b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"highlighted-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <h2 class=\"ui-e--highlighted-text\">\n            <span class=\"ui-e-headline-text elementor-repeater-item-59b8ee8\">Ervaar het potentieel van <\/span><span class=\"ui-e-headline-text elementor-repeater-item-8add9ac ui-e-headline-stroke1\">\n\t\t\t\t\t\t\t\t\t<span class=\"whitespace\"><\/span>\n                                    <span>\n                                        <span class=\"ui-e-headline-text ui-e-headline-highlighted\">XLine.<\/span><span class=\"uicore-svg-wrapper\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 500 150\" preserveAspectRatio=\"none\"><path d='M15.2,133.3L15.2,133.3c121.9-7.6,244-9.9,366.1-6.8c34.6,0.9,69.1,2.3,103.7,4' \/><\/svg><\/span><\/span> <span class=\"whitespace\"> <\/span><\/span>        <\/h2>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8993b86 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"8993b86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Het XLine platform verbindt naadloos elke gespecialiseerde module, ontworpen om een specifiek proces, workflow of afdeling te ondersteunen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c9ac29 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"2c9ac29\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contacteer ons<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Innovatieve Oplossingen voor Slimmere Gezondheidszorg. Met meer dan 20 jaar expertise zetten wij ons in om uw werk eenvoudiger en veiliger te [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-10734","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>startpagina - Aexis Medical<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aexis-medical.com\/de\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"startpagina - Aexis Medical\" \/>\n<meta property=\"og:description\" content=\"Innovatieve Oplossingen voor Slimmere Gezondheidszorg. Met meer dan 20 jaar expertise zetten wij ons in om uw werk eenvoudiger en veiliger te [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aexis-medical.com\/de\/\" \/>\n<meta property=\"og:site_name\" content=\"Aexis Medical\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T17:40:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aexis-medical.com\/de\/\",\"url\":\"https:\/\/aexis-medical.com\/de\/\",\"name\":\"startpagina - Aexis Medical\",\"isPartOf\":{\"@id\":\"https:\/\/aexis-medical.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aexis-medical.com\/de\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aexis-medical.com\/de\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp\",\"datePublished\":\"2022-06-07T17:27:29+00:00\",\"dateModified\":\"2026-03-23T17:40:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/aexis-medical.com\/de\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aexis-medical.com\/de\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/aexis-medical.com\/de\/#primaryimage\",\"url\":\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp\",\"contentUrl\":\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aexis-medical.com\/de\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aexis-medical.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"startpagina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aexis-medical.com\/#website\",\"url\":\"https:\/\/aexis-medical.com\/\",\"name\":\"Aexis Medical\",\"description\":\"Software for Hospitals\",\"publisher\":{\"@id\":\"https:\/\/aexis-medical.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aexis-medical.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aexis-medical.com\/#organization\",\"name\":\"Aexis Medical\",\"url\":\"https:\/\/aexis-medical.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/aexis-medical.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/logo.png\",\"contentUrl\":\"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/logo.png\",\"width\":3140,\"height\":632,\"caption\":\"Aexis Medical\"},\"image\":{\"@id\":\"https:\/\/aexis-medical.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"startpagina - Aexis Medical","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aexis-medical.com\/de\/","og_locale":"nl_NL","og_type":"article","og_title":"startpagina - Aexis Medical","og_description":"Innovatieve Oplossingen voor Slimmere Gezondheidszorg. Met meer dan 20 jaar expertise zetten wij ons in om uw werk eenvoudiger en veiliger te [&hellip;]","og_url":"https:\/\/aexis-medical.com\/de\/","og_site_name":"Aexis Medical","article_modified_time":"2026-03-23T17:40:54+00:00","og_image":[{"url":"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"12 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aexis-medical.com\/de\/","url":"https:\/\/aexis-medical.com\/de\/","name":"startpagina - Aexis Medical","isPartOf":{"@id":"https:\/\/aexis-medical.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aexis-medical.com\/de\/#primaryimage"},"image":{"@id":"https:\/\/aexis-medical.com\/de\/#primaryimage"},"thumbnailUrl":"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp","datePublished":"2022-06-07T17:27:29+00:00","dateModified":"2026-03-23T17:40:54+00:00","breadcrumb":{"@id":"https:\/\/aexis-medical.com\/de\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aexis-medical.com\/de\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/aexis-medical.com\/de\/#primaryimage","url":"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp","contentUrl":"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/09\/az-alma-logo.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/aexis-medical.com\/de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aexis-medical.com\/de\/"},{"@type":"ListItem","position":2,"name":"startpagina"}]},{"@type":"WebSite","@id":"https:\/\/aexis-medical.com\/#website","url":"https:\/\/aexis-medical.com\/","name":"Aexis Medical","description":"Software for Hospitals","publisher":{"@id":"https:\/\/aexis-medical.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aexis-medical.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/aexis-medical.com\/#organization","name":"Aexis Medical","url":"https:\/\/aexis-medical.com\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/aexis-medical.com\/#\/schema\/logo\/image\/","url":"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/logo.png","contentUrl":"https:\/\/aexis-medical.com\/wp-content\/uploads\/2024\/03\/logo.png","width":3140,"height":632,"caption":"Aexis Medical"},"image":{"@id":"https:\/\/aexis-medical.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aexis-medical.com\/nl\/wp-json\/wp\/v2\/pages\/10734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aexis-medical.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aexis-medical.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aexis-medical.com\/nl\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/aexis-medical.com\/nl\/wp-json\/wp\/v2\/comments?post=10734"}],"version-history":[{"count":25,"href":"https:\/\/aexis-medical.com\/nl\/wp-json\/wp\/v2\/pages\/10734\/revisions"}],"predecessor-version":[{"id":11416,"href":"https:\/\/aexis-medical.com\/nl\/wp-json\/wp\/v2\/pages\/10734\/revisions\/11416"}],"wp:attachment":[{"href":"https:\/\/aexis-medical.com\/nl\/wp-json\/wp\/v2\/media?parent=10734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}